{"id":64275,"date":"2022-08-11T07:46:58","date_gmt":"2022-08-11T06:46:58","guid":{"rendered":"https:\/\/www.iispv.cat\/oferta-de-treball\/ic49_22-tecnoleg-a-en-biomedicina-bioquimica-o-en-lambit-de-la-nutricio-i-metabolisme\/"},"modified":"2022-10-24T07:34:20","modified_gmt":"2022-10-24T06:34:20","slug":"ic49_22-tecnoleg-a-en-biomedicina-bioquimica-o-en-lambit-de-la-nutricio-i-metabolisme","status":"publish","type":"oferta_de_treball","link":"https:\/\/www.iispv.cat\/en\/oferta-de-treball\/ic49_22-tecnoleg-a-en-biomedicina-bioquimica-o-en-lambit-de-la-nutricio-i-metabolisme\/","title":{"rendered":"IC49_22 TECN\u00d2LEG\/A EN BIOMEDICINA, BIOQU\u00cdMICA O EN L\u2019\u00c0MBIT DE LA NUTRICI\u00d3 I METABOLISME (PROGRAMA INVESTIGO)"},"content":{"rendered":"","protected":false},"template":"","organitzacio_oferta":[],"class_list":["post-64275","oferta_de_treball","type-oferta_de_treball","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.iispv.cat\/en\/wp-json\/wp\/v2\/oferta_de_treball\/64275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iispv.cat\/en\/wp-json\/wp\/v2\/oferta_de_treball"}],"about":[{"href":"https:\/\/www.iispv.cat\/en\/wp-json\/wp\/v2\/types\/oferta_de_treball"}],"wp:attachment":[{"href":"https:\/\/www.iispv.cat\/en\/wp-json\/wp\/v2\/media?parent=64275"}],"wp:term":[{"taxonomy":"organitzacio_oferta","embeddable":true,"href":"https:\/\/www.iispv.cat\/en\/wp-json\/wp\/v2\/organitzacio_oferta?post=64275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}